{"id":6496,"date":"2021-09-16T15:39:00","date_gmt":"2021-09-16T15:39:00","guid":{"rendered":"https:\/\/www.in516ht.com\/?post_type=posts_de&#038;p=6496"},"modified":"2021-10-26T09:51:14","modified_gmt":"2021-10-26T09:51:14","slug":"migration-oracle-snowflake","status":"publish","type":"posts_de","link":"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/","title":{"rendered":"Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-18 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:85%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-16 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<h5 class=\"wp-block-heading\">Serie: Migration von Oracle nach Snowflake, Teil 1<\/h5>\n\n\n\n<p><strong>Oracle<\/strong>&nbsp;geh\u00f6rt zu den f\u00fchrenden Datenbankmanagementsystemen f\u00fcr den Betrieb von Online-Transaktionsverarbeitungs- und Data-Warehousing-Systemen. Angesichts des zunehmenden Volumens, der Geschwindigkeit und der Vielfalt der Daten, die uns f\u00fcr moderne Analysen zur Verf\u00fcgung stehen, bietet Oracle jedoch&nbsp;nur <strong>begrenzte Skalierbarkeit, um wachsende Workloads zu unterst\u00fctzen<\/strong>.<\/p>\n\n\n\n<p>Die <a href=\"http:\/\/www.snowflake.com\/\"><strong>Data Cloud von Snowflake<\/strong><\/a><strong>&nbsp;<\/strong>hingegen&nbsp;<strong>l\u00e4sst sich auf eine Weise skalieren, die mit Oracle einfach nicht m\u00f6glich ist<\/strong>. Durch die Trennung von Rechen- und Speicherressourcen skaliert Snowflake automatisch und sofort mit seiner gemeinsam genutzten Multi-Cluster-Architektur. Sie erm\u00f6glicht den Zugriff auf eine praktisch unbegrenzte Anzahl gleichzeitiger Benutzer und Anwendungen, w\u00e4hrend die Leistung nicht beeintr\u00e4chtigt wird. Im Vergleich zu herk\u00f6mmlichen L\u00f6sungen wie Oracle<strong>&nbsp;erm\u00f6glicht Snowflake die Speicherung von Daten an einem einzigen Ort zu einem Bruchteil der Kosten<\/strong>.<\/p>\n\n\n\n<p>Trotz der weit verbreiteten Nutzung von Oracle und der Verf\u00fcgbarkeit von Oracle-Talenten bewegen sich viele Gesch\u00e4ftsanwendungen weg von Oracle und hin zu Snowflake \u2013 nicht nur wegen der \u00fcberlegenen Skalierbarkeit, sondern auch wegen anderer Vorteile, die Snowflake von herk\u00f6mmlichen Oracle-Umgebungen abhebt.<\/p>\n\n\n\n<p>Aus diesem Grund haben wir unsere Serie zur Migration von Oracle nach Snowflake gestartet, in der <strong>wir uns mit der&nbsp;Datenmigrationsstrategie befassen und erkl\u00e4ren, wie Metadaten, ETL-Skripte, gespeicherte Prozeduren und Funktionen migriert werden und worauf w\u00e4hrend des Prozesses zu achten ist<\/strong>. Dar\u00fcber hinaus zeigen wir Ihnen einige wirklich beeindruckende&nbsp;<strong>Vergleiche aus unseren j\u00fcngsten Projekten<\/strong>.<\/p>\n\n\n\n<p>Wir beginnen mit den Vorteilen von Snowflake im Vergleich zu Oracle, die die Frage nach den Gr\u00fcnden f\u00fcr eine Migration beantworten und im folgenden Abschnitt n\u00e4her erl\u00e4utert werden.<\/p>\n\n\n\n<p>Snowflake basiert auf einem&nbsp;<strong>As-a-Service-Bereitstellungsmodell&nbsp;<\/strong>in der Cloud, das sich selbst verwaltet, ohne dass herk\u00f6mmliche Datenbankverwaltungsrollen erforderlich sind. Snowflake&nbsp;<strong>reduziert die Komplexit\u00e4t durch integrierte Leistungsoptimierung, sodass keine manuelle Abfrageoptimierung erforderlich ist<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-group group-block has-background\" style=\"background-color:#f2f5f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"has-text-align-center has-text-color wp-block-heading\" style=\"color:#1e1e43\">Beschleunigen Sie Ihren Weg zur Snowflake<\/h2>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center has-background is-layout-flex wp-container-6 wp-block-columns-is-layout-flex\" style=\"background-color:#fefefe\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-gallery aligncenter columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" loading=\"lazy\" width=\"208\" height=\"244\" src=\"https:\/\/in516ht.com\/insight-website\/wp-content\/uploads\/2021\/09\/Starten-ihre-Snowflake-Reise.svg\" alt=\"\" data-id=\"6625\" data-full-url=\"https:\/\/in516ht.com\/insight-website\/wp-content\/uploads\/2021\/09\/Starten-ihre-Snowflake-Reise.svg\" data-link=\"https:\/\/in516ht.com\/de\/starten-sie-ihre-snowflake-reise\/starten-ihre-snowflake-reise\/\" class=\"wp-image-6625\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 style=\"margin-bottom: 0px;\">Snowflake Services\n<\/h2>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"margin-top: 0px;\">Mit wem k\u00f6nnte man sie besser erkunden als mit Snowflakes innovativstem Partner in der EMEA-Region<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/in516ht.com\/de\/\" style=\"border-radius:3px;background-color:#1e1e43\">Mehr<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<p>In einer Snowflake-Umgebung ist kein Workload-Management erforderlich, da sie \u00fcber eine&nbsp;<a href=\"https:\/\/docs.snowflake.com\/en\/user-guide\/warehouses-multicluster.html\"><strong>Multi-Cluster-Architektur<\/strong><\/a><strong> verf\u00fcgt, die es Ihnen erm\u00f6glicht, separate Compute-Cluster f\u00fcr unterschiedliche Workloads zu erstellen, um Ressourcenkonflikte zu vermeiden<\/strong>. All dies geschieht ohne manuelle Eingriffe von Datenbankadministratoren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bereits in der Cloud<\/h3>\n\n\n\n<p>Viele neue Datenquellen befinden sich bereits in der Cloud, was\u00a0<strong>effiziente Analysen erm\u00f6glicht und Investitionen in neue Infrastrukturen\u00a0zur Speicherung und Verarbeitung solcher Datenquellen\u00a0reduziert<\/strong>. Aus all diesen Quellen kann auf Daten zugegriffen werden, wobei ein direkter, geregelter und sicherer Datenaustausch in Echtzeit mit minimalen Datenkopier- und Verschiebevorg\u00e4ngen m\u00f6glich ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zahlen Sie nur das, was Sie nutzen<\/h3>\n\n\n\n<p>Die Kosten f\u00fcr Snowflake basieren auf einem Pay-as-you-go-Modell, das auf der Menge der verarbeiteten Daten und dem Workload basiert \u2013 was ganz einfach bedeutet, dass Sie nur f\u00fcr das bezahlen, was Sie auch nutzen. Dies&nbsp;<strong>unterscheidet sich deutlich von Oracle, wo eine Kapazit\u00e4tsplanung f\u00fcr On-Premises erforderlich ist<\/strong>&nbsp;und Sie immer das Risiko einer \u00dcber- oder Unterkonfiguration Ihres Systems eingehen. Das ist besonders kritisch, wenn mehrere Server ben\u00f6tigt werden, z. B. bei Hochverf\u00fcgbarkeitskonfigurationen, die h\u00e4ufig Overhead-Kapazit\u00e4t erfordern. Selbst wenn Sie auf den Oracle Cloud Service umsteigen, haben Sie ein \u00e4hnliches Risiko bei der Kapazit\u00e4tsplanung, da Rechenleistung und Speicherplatz pro Instanz festgelegt sind. Wenn Sie mehr Kapazit\u00e4t innerhalb eines Oracle Cloud Service ben\u00f6tigen, m\u00fcssen Sie in vordefinierten Inkrementen kaufen. Die elastische Speicher- und Compute-Architektur von Snowflake eliminiert dieses Risiko.<\/p>\n\n\n\n<p><a href=\"https:\/\/in516ht.com\/snowflake-pricing-example-size-matters\/\"><strong>Mehr \u00fcber die Preise von Snowflake erfahren Sie in unserem Blog<\/strong><\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Notfallwiederherstellung<\/h3>\n\n\n\n<p>Bei der&nbsp;<strong>Oracle-Datenbank gibt es mehrere Wiederherstellungsszenarien, von denen viele den Kauf zus\u00e4tzlicher Hardware<\/strong>, Softwarelizenzen und Netzwerkinfrastruktur&nbsp;erfordern. Mit Snowflake ist dies nicht notwendig, da&nbsp;<strong>Snowflake automatisch \u00fcber mehrere Verf\u00fcgbarkeitszonen hinweg synchronisiert wird<\/strong>. Es ist also kein manueller Verwaltungsaufwand Ihrerseits erforderlich.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Getrennte Entwicklungs- und Testumgebungen<\/h3>\n\n\n\n<p>&nbsp;<strong>Wenn Sie bei&nbsp;Oracle getrennte Entwicklungs- und Testumgebungen ben\u00f6tigen, brauchen Sie zus\u00e4tzliche Server, was mehr Infrastruktur und Verwaltungsaufwand bedeutet<\/strong>. Um eine neue Umgebung einzurichten, m\u00fcssen Administratoren m\u00fchsam Datenstrukturen und Daten aus einer Umgebung exportieren und dann in eine andere Umgebung importieren.<\/p>\n\n\n\n<p>Bei&nbsp;<strong>Snowflake ist dies nicht erforderlich, da Sie einfach eine weitere Datenbank in Ihrem Konto erstellen und diese f\u00fcr beliebige Zwecke, z. B. Entwicklung oder Tests,&nbsp;konfigurieren<\/strong> k\u00f6nnen. Dar\u00fcber hinaus k\u00f6nnen Sie mit der&nbsp;<a href=\"https:\/\/www.snowflake.com\/blog\/snowflake-fast-clone\/\"><strong>Snowflake-Klonfunktion<\/strong><\/a> die neue Datenbank sofort und ohne zus\u00e4tzliche Kosten mit einer vollst\u00e4ndigen Kopie der Daten f\u00fcllen.<\/p>\n\n\n\n<div class=\"wp-block-group group-block has-background\" style=\"background-color:#f2f5f7\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"has-text-align-center has-text-color wp-block-heading\" style=\"color:#1e1e43\">Webinar recording<\/h2>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center has-background is-layout-flex wp-container-13 wp-block-columns-is-layout-flex\" style=\"background-color:#fefefe\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-gallery aligncenter columns-1 is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" loading=\"lazy\" width=\"144\" height=\"149\" src=\"https:\/\/in516ht.com\/insight-website\/wp-content\/uploads\/2021\/09\/Zweitmeinung.svg\" alt=\"\" data-id=\"6688\" data-full-url=\"https:\/\/in516ht.com\/insight-website\/wp-content\/uploads\/2021\/09\/Zweitmeinung.svg\" data-link=\"https:\/\/in516ht.com\/de\/zweitmeinung\/zweitmeinung\/\" class=\"wp-image-6688\"\/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 style=\"margin-bottom: 0px;\">Oracle Exadata zu Snowflake\n<\/h2>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"margin-top: 0px;\">auf Englisch<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/in516ht.com\/de\/\" style=\"border-radius:3px;background-color:#1e1e43\">Mehr<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Standard-SQL<\/h3>\n\n\n\n<p><a href=\"https:\/\/www.snowflake.com\/blog\/ansi-sql-with-analytic-functions\/\"><strong>Snowflake ist ANSI SQL-konform<\/strong><\/a>&nbsp;und unterst\u00fctzt somit die Tools, die Millionen von Gesch\u00e4ftsanwender bereits heute erfolgreich nutzen. Dies sollte einen unkomplizierten \u00dcbergang von Oracle auf Snowflake erm\u00f6glichen.<\/p>\n\n\n\n<p>Zusammenfassend l\u00e4sst sich sagen, dass es&nbsp;<strong>viele zwingende Gr\u00fcnde gibt, von Oracle nach Snowflake zu migrieren.<\/strong>&nbsp;Sobald die Entscheidung zur Migration gefallen ist, beginnt die eigentliche Migrationsarbeit.<\/p>\n\n\n\n<p>In den folgenden Teilen dieser Serie werden wir verschiedene Aspekte der Migration von Oracle nach Snowflake untersuchen.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Maja Ferle, Senior Consultant<\/h5>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:65px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":6977,"template":"","categories":[20],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation - IN516HT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation - IN516HT\" \/>\n<meta property=\"og:description\" content=\"Serie: Migration von Oracle nach Snowflake, Teil 1 Oracle&nbsp;geh\u00f6rt zu den f\u00fchrenden Datenbankmanagementsystemen f\u00fcr den Betrieb von Online-Transaktionsverarbeitungs- und Data-Warehousing-Systemen. Angesichts des zunehmenden Volumens, der Geschwindigkeit und der Vielfalt der Daten, die uns f\u00fcr moderne Analysen zur Verf\u00fcgung stehen, bietet Oracle jedoch&nbsp;nur begrenzte Skalierbarkeit, um wachsende Workloads zu unterst\u00fctzen. Die Data Cloud von Snowflake&nbsp;hingegen&nbsp;l\u00e4sst sich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/\" \/>\n<meta property=\"og:site_name\" content=\"IN516HT\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-26T09:51:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/in516ht.com\/insight-website\/wp-content\/uploads\/2021\/09\/Migration-von-Oracle-nach-Snowflake.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/\",\"url\":\"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/\",\"name\":\"Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation - IN516HT\",\"isPartOf\":{\"@id\":\"https:\/\/in516ht.com\/#website\"},\"datePublished\":\"2021-09-16T15:39:00+00:00\",\"dateModified\":\"2021-10-26T09:51:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/in516ht.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/in516ht.com\/#website\",\"url\":\"https:\/\/in516ht.com\/\",\"name\":\"IN516HT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/in516ht.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation - IN516HT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/","og_locale":"de_DE","og_type":"article","og_title":"Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation - IN516HT","og_description":"Serie: Migration von Oracle nach Snowflake, Teil 1 Oracle&nbsp;geh\u00f6rt zu den f\u00fchrenden Datenbankmanagementsystemen f\u00fcr den Betrieb von Online-Transaktionsverarbeitungs- und Data-Warehousing-Systemen. Angesichts des zunehmenden Volumens, der Geschwindigkeit und der Vielfalt der Daten, die uns f\u00fcr moderne Analysen zur Verf\u00fcgung stehen, bietet Oracle jedoch&nbsp;nur begrenzte Skalierbarkeit, um wachsende Workloads zu unterst\u00fctzen. Die Data Cloud von Snowflake&nbsp;hingegen&nbsp;l\u00e4sst sich [&hellip;]","og_url":"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/","og_site_name":"IN516HT","article_modified_time":"2021-10-26T09:51:14+00:00","og_image":[{"width":1440,"height":450,"url":"https:\/\/in516ht.com\/insight-website\/wp-content\/uploads\/2021\/09\/Migration-von-Oracle-nach-Snowflake.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/","url":"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/","name":"Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation - IN516HT","isPartOf":{"@id":"https:\/\/in516ht.com\/#website"},"datePublished":"2021-09-16T15:39:00+00:00","dateModified":"2021-10-26T09:51:14+00:00","breadcrumb":{"@id":"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.in516ht.com\/de\/posts_de\/migration-oracle-snowflake\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/in516ht.com\/de\/"},{"@type":"ListItem","position":2,"name":"Migration von Oracle nach Snowflake: Einf\u00fchrung und Motivation"}]},{"@type":"WebSite","@id":"https:\/\/in516ht.com\/#website","url":"https:\/\/in516ht.com\/","name":"IN516HT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/in516ht.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/posts_de\/6496"}],"collection":[{"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/posts_de"}],"about":[{"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/types\/posts_de"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/media\/6977"}],"wp:attachment":[{"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/media?parent=6496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/categories?post=6496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}