{"id":6987,"date":"2021-09-17T09:22:53","date_gmt":"2021-09-17T09:22:53","guid":{"rendered":"https:\/\/www.in516ht.com\/?post_type=posts_de&#038;p=6987"},"modified":"2021-09-17T10:05:03","modified_gmt":"2021-09-17T10:05:03","slug":"beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an","status":"publish","type":"posts_de","link":"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/","title":{"rendered":"Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-2 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>In der nicht allzu fernen Vergangenheit war umfassendes Data Warehousing den gro\u00dfen Unternehmen vorbehalten \u2013 denjenigen, die sich die hohen Kosten f\u00fcr Hardware und Rechenleistung zur Unterst\u00fctzung eines Data Warehouse leisten konnten. Doch das war nur der Anfang der gro\u00dfen Vorabinvestitionen. Aufgrund der Komplexit\u00e4t der Plattformen ben\u00f6tigten Unternehmen auch einen oder mehrere Datenbankadministratoren und andere IT-Mitarbeiter, die die Ressourcen warten oder Softwarefehler beheben konnten.<\/p>\n\n\n\n<p><strong>Dann kam die <a href=\"http:\/\/www.snowflake.com\">Snowflake Data Cloud <\/a>&#8230;<\/strong><\/p>\n\n\n\n<p>&#8230; und die Zeiten \u00e4nderten sich (mehr dazu k\u00f6nnen Sie hier lesen). Unternehmen jeder Gr\u00f6\u00dfe k\u00f6nnen jetzt das kosteneffiziente Data Warehouse erhalten, das sie ben\u00f6tigen. Dabei geht es nicht nur um die anf\u00e4nglichen Investitionskosten, sondern auch um versteckte Geb\u00fchren, Quoten und andere Strafgelder, die sich fr\u00fcher oder sp\u00e4ter als frustrierend erweisen. Und wenn Sie Budgets und Gesch\u00e4ftspl\u00e4ne haben, die Sie einhalten m\u00fcssen, ist eine klare Preisgestaltung f\u00fcr den Betrieb Ihrer Cloud-Plattform etwas, wof\u00fcr Sie sehr dankbar sind.<\/p>\n\n\n\n<p>Mit Snowflake k\u00f6nnen Sie die Folgekosten vergessen, die bei der Bereitstellung und dem Betrieb eines Warehouse selten korrekt berechnet werden:<\/p>\n\n\n\n<p>Es muss weder Hardware installiert noch ein Betriebssystem oder eine Datenbanksoftware bereitgestellt werden. Es sind keine Patches anzuwenden oder Datenbank-Upgrades zu planen. Nahezu Null-Management bei der Einrichtung.<\/p>\n\n\n\n<p>Keine feste Geb\u00fchr pro Benutzer oder pro CPU-Kern. Bei Snowflake gibt es keine festen Geb\u00fchren \u2013 alle Geb\u00fchren sind nutzungsabh\u00e4ngig.<\/p>\n\n\n\n<p>Keine versteckten Quoten oder Preiserh\u00f6hungen. Wenn Sie Abfragen in Snowflake durchf\u00fchren, gibt es keine zus\u00e4tzlichen Nutzungsquoten oder versteckten Preisaufschl\u00e4ge. Sie zahlen nur f\u00fcr das, was Sie auch nutzen.<\/p>\n\n\n\n<p>Wenn keine Abfragen aktiv sind, k\u00f6nnen Sie Ihr Warehouse automatisch in den Aussetzungsmodus versetzen. Nach der Aussetzung werden auch die Geb\u00fchren f\u00fcr nicht genutzte Rechenzeit ausgesetzt.<\/p>\n\n\n\n<p>Hier eine detailliertere Erl\u00e4uterung:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Snowflake bietet ein einfaches Preismodell.<\/h2>\n\n\n\n<p>Snowflake hilft Ihnen, Ihr Budget ganz einfach, kosteng\u00fcnstig und effizient zu verwalten. Das Preismodell umfasst zwei Hauptteile: die Kosten f\u00fcr den Speicherplatz und die Kosten f\u00fcr die verbrauchten Rechenressourcen:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die Geb\u00fchren f\u00fcr den Speicherplatz pro Terabyte \u2013 komprimiert \u2013 pro Monat.<\/h3>\n\n\n\n<p>Die Snowflake-Speicherkosten k\u00f6nnen bei einer Pauschale von 23 $\/TB \u2013 durchschnittliche komprimierte Menge \u2013 pro Monat beginnen, die t\u00e4glich kumuliert werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Die Geb\u00fchren f\u00fcr die Rechenleistung eines virtuellen Warehouse, das es Ihnen erm\u00f6glicht, Daten zu laden und Abfragen vorzunehmen.<\/h3>\n\n\n\n<p>Sie k\u00f6nnen eine beliebige Anzahl virtueller Warehouses und aus acht \u201eT-Shirt\u201c-Gr\u00f6\u00dfen ausw\u00e4hlen: X-Small, Small, Medium, Large, und X- bis 6X-Large. Je gr\u00f6\u00dfer die Gr\u00f6\u00dfe, desto schneller Ihr Computing. Sie k\u00f6nnen die Gr\u00f6\u00dfe in Sekundenschnelle vergr\u00f6\u00dfern oder verkleinern und ganz leicht verschiedene Gr\u00f6\u00dfen f\u00fcr einzelne Benutzer festlegen.<\/p>\n\n\n\n<p>Kunden zahlen f\u00fcr virtuelle Warehouses mit Snowflake Credits.<\/p>\n\n\n\n<p><strong>Es gibt zwei zus\u00e4tzliche Funktionen, f\u00fcr die Snowflake Credits verwendet werden:<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cloud-Dienste<\/h3>\n\n\n\n<p>Wie im Snowflake-Preisleitfaden beschrieben: \u201eDie Cloud-Dienste sorgen f\u00fcr das permanente Statusmanagement und die Gesamtkoordination von Snowflake. Die Kunden zahlen f\u00fcr Cloud-Dienste mit Snowflake Credits. Die Ressourcen f\u00fcr Cloud-Dienste werden von Snowflake automatisch auf der Grundlage der Anforderungen des Workloads zugewiesen. Die normale Nutzung von Cloud-Diensten (bis zu 10 % der t\u00e4glichen Compute Credits) ist kostenlos, was bedeutet, dass den meisten Kunden keine zus\u00e4tzlichen Kosten f\u00fcr die Nutzung von Cloud-Diensten entstehen.\u201c<\/p>\n\n\n\n<p>Abgesehen davon werden Ihre Credits auch verwendet, wenn Sie Folgendes nutzen:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Serverlose Funktionen<\/h3>\n\n\n\n<p>Snowpipe (schneller Eingang von Streaming-Daten), Datenbankreplikation (Replikation Ihrer Daten \u00fcber Regionen und Cloud-Plattformen hinweg), Materialized Views Maintenance, automatisches Clustering und Suchmaschinenoptimierung. Hier erfahren Sie mehr \u00fcber die Abrechnung serverloser Funktionen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Snowflake Credits<\/h2>\n\n\n\n<p>Credits werden verwendet, um f\u00fcr den Verbrauch von Ressourcen in Snowflake zu bezahlen. Ein Snowflake Credit ist eine Ma\u00dfeinheit, die nur dann verbraucht wird, wenn ein Kunde Rechenressourcen nutzt.<\/p>\n\n\n\n<p>Die Kosten f\u00fcr ein Credit beginnen bei 2 $ \u2013 je nach Ihrer Region, dem bevorzugten Cloud-Anbieter (Azure, AWS, Google Cloud Platform) und der gew\u00e4hlten Snowflake-Plattformversion (Standard, Enterprise usw.).<\/p>\n\n\n\n<p>F\u00fcr jede der genannten Data-Warehouse-Gr\u00f6\u00dfen gibt es einen speziellen Compute Credit. Mit zunehmender Gr\u00f6\u00dfe variiert auch der Verbrauch der Credits.<\/p>\n\n\n\n<p>Sie haben zwei Optionen, die Dienste zu erwerben \u2013 die eine ist die On-Demand-Variante, die flexibelste und einfachste Methode, da Sie einen Festpreis f\u00fcr die genutzten Dienste zahlen, der jeden Monat nachtr\u00e4glich abgerechnet wird. Die andere Option ist, dass Sie die gew\u00fcnschte Kapazit\u00e4t im Voraus kaufen und sie dann monatlich nutzen. Letztere Option bieten Ihnen mehr Serviceoptionen, niedrigere Preise und eine langfristige Preisgarantie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Beispiel: Oftmals reicht ein eXtra Small aus.<\/h2>\n\n\n\n<p>Nehmen wir ein Beispiel aus einem osteurop\u00e4ischen Markt, in dem die Mehrheit der kleinen und mittleren Unternehmen Microsoft SQL Server f\u00fcr ihr Data Warehouse verwenden, da es kosteng\u00fcnstig ist. Der Kunde hat mehr als 50 Dimensionen, mehr als 10 Faktentabellen und einige Quellen, bei denen das gesamte Faktenvolumen weniger als 200 Millionen betr\u00e4gt.<\/p>\n\n\n\n<p>Nehmen wir an, ein Unternehmen w\u00e4hlt zwischen zwei Snowflake-Plattformversionen \u2013 Standard und Enterprise. Wir werden an anderer Stelle auf die Unterschiede zwischen den Plattformen eingehen, f\u00fcr den Moment sei nur gesagt, dass der gr\u00f6\u00dfte Vorteil der Enterprise-Version darin besteht, dass sie Time Travel und die automatische horizontale Skalierung erm\u00f6glicht und Ihnen den Zugriff auf historische Daten (d. h. Daten, die ge\u00e4ndert oder gel\u00f6scht wurden) zu einem beliebigen Zeitpunkt innerhalb eines festgelegten Zeitraums erlaubt. Sie kann zum Beispiel datenbezogene Objekte (Tabellen, Schemata und Datenbanken) wiederherstellen, die versehentlich oder absichtlich gel\u00f6scht wurden (mehr zu Time Travel). In der Azure-Cloud betr\u00e4gt der Preis f\u00fcr ein Credit bei der Standard-Version 2 $ und 3,7 $ bei der Enterprise-Version. Berechnen wir zun\u00e4chst, wie viele Credits das Unternehmen ben\u00f6tigt:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Speicherplatz<\/h3>\n\n\n\n<p>Die Speicherkosten werden anhand der monatlichen Speichernutzung \u2013 nach Komprimierung \u2013 f\u00fcr alle in Snowflake gespeicherten Kundendaten berechnet. In unserem Fall w\u00e4re 1 TB genug Speicherplatz, also beliefen sich die Kosten f\u00fcr den Speicherplatz auf:<\/p>\n\n\n\n<p>1 TB x 23 $ x 12 Monate = 276 $ pro Jahr<\/p>\n\n\n\n<p>Da Snowflake spaltenbasierten Speicher verwendet und hohe Komprimierungsraten aufweist, kann eine Zeitreihen-Faktentabelle mit 7 Spalten und 5B-Zeilen nur 100 GB gro\u00df sein.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rechenleistung<\/h3>\n\n\n\n<p>Die Mitarbeiter arbeiten nicht das ganze Jahr \u00fcber, sondern nur an Wochentagen, sodass wir von 260 Tagen pro Jahr ausgehen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">ELT-Produktion<\/h3>\n\n\n\n<p>Mit dem \u00dcbergang zum Cloud-basierten Data Warehousing haben sich immer mehr ELT-Ans\u00e4tze im Vergleich zu ETL durchgesetzt. Das bedeutet, dass zun\u00e4chst alles in das Zielsystem geladen wird und erst danach alle Transformationen durchgef\u00fchrt werden. F\u00fcr die t\u00e4gliche Extraktion, das Laden und die Transformation von Daten in Snowflake, die auf einem Cluster der Gr\u00f6\u00dfe XS laufen, ben\u00f6tigt das Unternehmen 3 Stunden pro Tag.<\/p>\n\n\n\n<p>3 (Stunden pro Tag) * 260 (Tage pro Jahr) * 1 (Credits f\u00fcr XS-Gr\u00f6\u00dfe) = 780 Credits pro Jahr<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pr\u00fcfung und Entwicklung<\/h3>\n\n\n\n<p>F\u00fcr Entwickler, die an der Gewinnung der erforderlichen, aus dem Gesch\u00e4ft abgeleiteten Erkenntnisse beteiligt sind, wird ebenfalls ein separates Warehouse f\u00fcr die Entwicklung in Gr\u00f6\u00dfe XS eingerichtet. Sie werden es 4 Stunden pro Tag in Gr\u00f6\u00dfe XS betreiben:<\/p>\n\n\n\n<p>4 (Stunden pro Tag) * 260 (Tage pro Jahr) * 1 (Credits f\u00fcr XS-Gr\u00f6\u00dfe) = 1040 Credits pro Jahr<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">BI-Produktion<\/h3>\n\n\n\n<p>Die BI-Abteilung wird die meiste Zeit auf der Plattform verbringen und Berichte und Analysen ausf\u00fchren. Nehmen wir an, wir haben bis zu 5 gleichzeitige Benutzer (die Abfragen in der gleichen Sekunde parallel ausf\u00fchren) oder 50 Standard-BI-Benutzer. Da Snowflake nur die Verarbeitungszeit berechnet, die bei der Verwendung von BI-Tools mit In-Memory-Datenbanken wie Tableau erheblich reduziert werden kann, legt das Unternehmen f\u00fcr das Team 5 Stunden Non-Stop-Nutzung pro Tag fest (denken Sie daran, dass Sie die Nutzung nach der Inaktivit\u00e4tsphase automatisch aussetzen k\u00f6nnen und dass das XS-Cluster eine Sekunde zum Starten ben\u00f6tigt).<\/p>\n\n\n\n<p>5 (Stunden pro Tag) * 260 (Tage pro Jahr) * 1 (Credits f\u00fcr XS-Gr\u00f6\u00dfe) = 1300 Credits pro Jahr<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gesamt<\/h2>\n\n\n\n<p><strong>780 Credits (ETL-Produktion) + 1.040 Credits (Entwicklung) + 1.300 Credits (BI) = 3.120 Credits<\/strong><\/p>\n\n\n\n<p>Nachdem wir nun die Anzahl der Credits berechnet haben, die sie im Jahr ben\u00f6tigen, wissen wir, wie viel jede Plattform kosten wird. Wie bereits zu Beginn erw\u00e4hnt, betr\u00e4gt der Preis f\u00fcr ein Credit bei der Standard-Version 2 $ und bei der Enterprise-Version 3,7 $.<\/p>\n\n\n\n<p><strong>Standard: 3.120 Credits x 2 $ = 6.240 $<\/strong><\/p>\n\n\n\n<p><strong>Enterprise: 3.120 Credits x 3,7 $ = 11.544 $<\/strong><\/p>\n\n\n\n<p>Addieren Sie nun die 276 $ f\u00fcr den Speicherplatz hinzu, und Sie haben die Gesamtkosten pro Jahr!<\/p>\n\n\n\n<p>Rechnet man nun noch die erforderlichen Personalkosten f\u00fcr die Verwaltung und Optimierung der bestehenden L\u00f6sung hinzu, die bei Snowflake fast bei 0 liegen, so ergeben sich bessere Gesamtkosten f\u00fcr ein System im Vergleich zu Snowflake. Basierend auf unseren Erfahrungen und den aktuellen Kosten ist es auch deutlich g\u00fcnstiger als die Verwendung der Standardversion von Microsoft SQL Server.<\/p>\n\n\n\n<p>Anmerkung: Da das Unternehmen in unserem Fall \u00fcber 1 TB an Daten verf\u00fcgte, verwendeten wir die XS-Gr\u00f6\u00dfe auf einem einzigen Cluster. Das ist tats\u00e4chlich mehr als genug f\u00fcr die Gr\u00f6\u00dfe, da es bis zu 100 Millionen Zeilen in Sekunden verarbeiten kann. Zum besseren Verst\u00e4ndnis der Kosten: F\u00fcr Ihr Warehouse in Gr\u00f6\u00dfe XS werden Sie einen Credit pro Stunde nutzen, in Gr\u00f6\u00dfe S zwei, in Gr\u00f6\u00dfe M vier, usw.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">M\u00f6chten Sie mehr \u00fcber Ihren spezifischen Fall erfahren?<\/h3>\n\n\n\n<h3 class=\"has-text-color wp-block-heading\" style=\"color:#0096f2\">Kostenloses 2-st\u00fcndiges Informationsgespr\u00e4ch.<\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"menu-button\" style=\"margin: 0px;\"><a href=\"#\" data-toggle=\"modal\" data-target=\"#get-in-touch\" title=\"Get in touch\">Get in touch<\/a><\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Wir sind einer der erfahrensten und langj\u00e4hrigsten europ\u00e4ischen Snowflake-Partner und wurden von Snowflake mit einem \u201ePerson des Jahres\u201c-Award f\u00fcr Mittel- und Osteuropa ausgezeichnet. Wir sind eines der f\u00fchrenden Unternehmen im Bereich Datenmanagement, Datenintegration und BI. Wir k\u00f6nnen Ihnen dabei helfen, alle Ihre Daten zusammenzuf\u00fchren und allen Benutzern zu erm\u00f6glichen, innovative Analysen durchzuf\u00fchren.<\/p>\n<\/div>\n<\/div>\n","protected":false},"featured_media":6988,"template":"","categories":[19],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an - IN516HT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an - IN516HT\" \/>\n<meta property=\"og:description\" content=\"In der nicht allzu fernen Vergangenheit war umfassendes Data Warehousing den gro\u00dfen Unternehmen vorbehalten \u2013 denjenigen, die sich die hohen Kosten f\u00fcr Hardware und Rechenleistung zur Unterst\u00fctzung eines Data Warehouse leisten konnten. Doch das war nur der Anfang der gro\u00dfen Vorabinvestitionen. Aufgrund der Komplexit\u00e4t der Plattformen ben\u00f6tigten Unternehmen auch einen oder mehrere Datenbankadministratoren und andere [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/\" \/>\n<meta property=\"og:site_name\" content=\"IN516HT\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-17T10:05:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/in516ht.com\/insight-website\/wp-content\/uploads\/2021\/09\/Data-Warehouse-Migration-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/\",\"url\":\"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/\",\"name\":\"Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an - IN516HT\",\"isPartOf\":{\"@id\":\"https:\/\/in516ht.com\/#website\"},\"datePublished\":\"2021-09-17T09:22:53+00:00\",\"dateModified\":\"2021-09-17T10:05:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/in516ht.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/in516ht.com\/#website\",\"url\":\"https:\/\/in516ht.com\/\",\"name\":\"IN516HT\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/in516ht.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an - IN516HT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/","og_locale":"de_DE","og_type":"article","og_title":"Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an - IN516HT","og_description":"In der nicht allzu fernen Vergangenheit war umfassendes Data Warehousing den gro\u00dfen Unternehmen vorbehalten \u2013 denjenigen, die sich die hohen Kosten f\u00fcr Hardware und Rechenleistung zur Unterst\u00fctzung eines Data Warehouse leisten konnten. Doch das war nur der Anfang der gro\u00dfen Vorabinvestitionen. Aufgrund der Komplexit\u00e4t der Plattformen ben\u00f6tigten Unternehmen auch einen oder mehrere Datenbankadministratoren und andere [&hellip;]","og_url":"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/","og_site_name":"IN516HT","article_modified_time":"2021-09-17T10:05:03+00:00","og_image":[{"width":1440,"height":450,"url":"https:\/\/in516ht.com\/insight-website\/wp-content\/uploads\/2021\/09\/Data-Warehouse-Migration-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/","url":"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/","name":"Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an - IN516HT","isPartOf":{"@id":"https:\/\/in516ht.com\/#website"},"datePublished":"2021-09-17T09:22:53+00:00","dateModified":"2021-09-17T10:05:03+00:00","breadcrumb":{"@id":"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.in516ht.com\/de\/posts_de\/beispiel-fuer-snowflake-preise-auf-die-groesse-kommt-es-an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/in516ht.com\/de\/"},{"@type":"ListItem","position":2,"name":"Beispiel f\u00fcr Snowflake-Preise: Auf die Gr\u00f6\u00dfe kommt es an"}]},{"@type":"WebSite","@id":"https:\/\/in516ht.com\/#website","url":"https:\/\/in516ht.com\/","name":"IN516HT","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/in516ht.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"}]}},"_links":{"self":[{"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/posts_de\/6987"}],"collection":[{"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/posts_de"}],"about":[{"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/types\/posts_de"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/media\/6988"}],"wp:attachment":[{"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/media?parent=6987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.in516ht.com\/de\/wp-json\/wp\/v2\/categories?post=6987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}